{"id":241,"date":"2013-05-14T15:55:16","date_gmt":"2013-05-14T13:55:16","guid":{"rendered":"https:\/\/www.familie-papp.de\/reisen\/?p=241"},"modified":"2020-08-03T13:14:42","modified_gmt":"2020-08-03T11:14:42","slug":"4-park-guell-und-berg-tibidabo","status":"publish","type":"post","link":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/","title":{"rendered":"4. Park G\u00fcell und Berg Tibidabo"},"content":{"rendered":"<table border=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td style=\"text-align: left;\"><a title=\"3. Parc de la Ciutadella, Catedral, Arc de Triomf\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-barcelona\/3-parc-de-la-ciutadella-catedral-arc-de-triomf\/\">\u2039\u00a0Zur\u00fcck<\/a><\/td>\n<td style=\"text-align: center;\"><a title=\"2013 Barcelona \u2013 \u00dcbersicht \u00fcber den Reiseverlauf\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/\">Reiseverlauf<\/a><\/td>\n<td style=\"text-align: right;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>ngg_shortcode_0_placeholder An unserem letzten Tag haben wir den Park G\u00fcell und den Hausberg von Barcelona Tibidabo und die\u00a0Kirche Sagrat Cor besichtigt. Um den Parc G\u00fcell zu sehen, lohnt es sich an der Metrostation Vallcarca auszusteigen. Von hier aus fahren Rolltreppen bis zu einem Eingang des Parks, von dem aus man gleich zum h\u00f6chsten Punkt mit Gipfelkreuz gelangen kann. Von hier aus l\u00e4uft man dann ganz bequem zu der ber\u00fchmten zentralen gro\u00dfe Freitreppe und zum Terrassenplatz\u00a0Platz mit den Pf\u00f6rtnerh\u00e4uschen. Im Park erkennt man die k\u00fcnstlerische Hand\u00a0Gaud\u00eds wieder. Die St\u00fctzpfeiler der Terassen und die Figuren wirken sehr organisch und sind der Natur nachempfunden. Wir haben auch das Wohnhaus\u00a0Gaud\u00eds besichtigt, das\u00a0Casa-Museu Gaud\u00ed. Hier haben wir mit Rabatt noch mal 5 \u20ac pro Person gezahlt und konnten einige M\u00f6bel und Zeichnungen bewundern. Wenn man Zeit hat, kann man sich das durchaus anschauen, allerdings gibt es schon recht wenig zu sehen.<\/p>\n<p>ngg_shortcode_1_placeholder Absolutes Highlight war der Besuch des Tibidabo. Um\u00a0auf den Berg zu gelangen muss man, nachdem man aus der S-Bahn-Station kommt mit der alten Tramvia Blau durch das Nobelviertel\u00a0Avenue Tibidabo\u00a0mit zahlreichen pr\u00e4chtigen Villen zur historischen\u00a0Standseilbahn (Funicular de Tibidabo, leider nicht bei der BC dabei) fahren. Die historische Stra\u00dfenbahnfahrt kostet aber noch mal ca. 6 \u20ac pro Person. Zwei Meter weiter h\u00e4lt ein normaler\u00a0Linienbus\u00a0der die selbe Strecke f\u00e4hrt und um einiges billiger und in der BC eh schon enthalten ist. Meist steht hier aber auch jemand der das den Touristen noch mal erkl\u00e4rt. Den Freizeitpark muss man nicht besuchen, die Attraktionen sind eher was f\u00fcr Kinder. Wir haben auf der Sonnenterrasse einen Kaffee getrunken. Im Anschluss haben wir die Kirche Sagrat Cor angeschaut. \u00dcber einen Fahrstuhl (nur zwei \u20ac pro Person, Tickets kann man an einem Automaten kaufen) und noch weitere Treppen erreicht man eine kleine Aussichtsplattform direkt zu F\u00fc\u00dfen der Jesus-Statue auf dem Dach der Kirche.\u00a0Von hier aus hatten wir den mit Abstand fantastischsten Blick auf die Stadt. Man ist hier wirklich auf dem h\u00f6chsten Punkt und kann bei klarem Wetter ganz Barcelona und das Hinterland bestaunen. Es ist sogar noch h\u00f6her als der Fernsehturm\u00a0Torre de Collserola. Zu dem konnte man praktisch r\u00fcber laufen und mit der Barcelona Card auch kostenlos mit einem gl\u00e4sernen Fahrstuhl rauf fahren. Aber da wir schon auf der Kirche waren, haben wir das nicht mehr gemacht.<\/p>\n<h3>Berg Tibidabo<\/h3>\nngg_shortcode_2_placeholder\n<h3>Bilder<\/h3>\nngg_shortcode_3_placeholder\n<h3><span style=\"font-size: 1.17em;\">Karte<\/span><\/h3>\n\n<table border=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td style=\"text-align: left;\"><a title=\"3. Parc de la Ciutadella, Catedral, Arc de Triomf\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-barcelona\/3-parc-de-la-ciutadella-catedral-arc-de-triomf\/\">\u2039\u00a0Zur\u00fcck<\/a><\/td>\n<td style=\"text-align: center;\"><a title=\"2013 Barcelona \u2013 \u00dcbersicht \u00fcber den Reiseverlauf\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/\">Reiseverlauf<\/a><\/td>\n<td style=\"text-align: right;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>An unserem letzten Tag haben wir den Park G\u00fcell und den Hausberg von Barcelona Tibidabo und die Kirche Sagrat Cor besichtigt. Um den Parc G\u00fcell zu sehen, lohnt es sich an der Metrostation Vallcarca auszusteigen. <a class=\"more-link\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/\"><span class=\"screen-reader-text\">  4. Park G\u00fcell und Berg Tibidabo<\/span> weiterlesen<span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":243,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2013-spanien-barcelona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4. Park G\u00fcell und Berg Tibidabo - Reiseberichte<\/title>\n<meta name=\"description\" content=\"An unserem letzten Tag haben wir den Park G\u00fcell und den Hausberg von Barcelona Tibidabo und die Kirche Sagrat Cor besichtigt. Um den Parc G\u00fcell zu sehen, lohnt es sich an der Metrostation Vallcarca auszusteigen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4. Park G\u00fcell und Berg Tibidabo - Reiseberichte\" \/>\n<meta property=\"og:description\" content=\"An unserem letzten Tag haben wir den Park G\u00fcell und den Hausberg von Barcelona Tibidabo und die Kirche Sagrat Cor besichtigt. Um den Parc G\u00fcell zu sehen, lohnt es sich an der Metrostation Vallcarca auszusteigen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/\" \/>\n<meta property=\"og:site_name\" content=\"Reiseberichte\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-14T13:55:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-03T11:14:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2013-barcelona-4-tibidabo-Beitragsbild-e1368539786361.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"133\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@chris_papp_de\" \/>\n<meta name=\"twitter:site\" content=\"@chris_papp_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chris\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/4-park-guell-und-berg-tibidabo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/4-park-guell-und-berg-tibidabo\\\/\"},\"author\":{\"name\":\"Chris\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#\\\/schema\\\/person\\\/5c31a83093ce724f3bf8ae666747d594\"},\"headline\":\"4. Park G\u00fcell und Berg Tibidabo\",\"datePublished\":\"2013-05-14T13:55:16+00:00\",\"dateModified\":\"2020-08-03T11:14:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/4-park-guell-und-berg-tibidabo\\\/\"},\"wordCount\":445,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/4-park-guell-und-berg-tibidabo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2013-barcelona-4-tibidabo-Beitragsbild-e1368539786361.jpg\",\"articleSection\":[\"2013 Spanien - Barcelona\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/4-park-guell-und-berg-tibidabo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/4-park-guell-und-berg-tibidabo\\\/\",\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/4-park-guell-und-berg-tibidabo\\\/\",\"name\":\"4. Park G\u00fcell und Berg Tibidabo - Reiseberichte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/4-park-guell-und-berg-tibidabo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/4-park-guell-und-berg-tibidabo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2013-barcelona-4-tibidabo-Beitragsbild-e1368539786361.jpg\",\"datePublished\":\"2013-05-14T13:55:16+00:00\",\"dateModified\":\"2020-08-03T11:14:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#\\\/schema\\\/person\\\/5c31a83093ce724f3bf8ae666747d594\"},\"description\":\"An unserem letzten Tag haben wir den Park G\u00fcell und den Hausberg von Barcelona Tibidabo und die Kirche Sagrat Cor besichtigt. Um den Parc G\u00fcell zu sehen, lohnt es sich an der Metrostation Vallcarca auszusteigen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/4-park-guell-und-berg-tibidabo\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/4-park-guell-und-berg-tibidabo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/4-park-guell-und-berg-tibidabo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2013-barcelona-4-tibidabo-Beitragsbild-e1368539786361.jpg\",\"contentUrl\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2013-barcelona-4-tibidabo-Beitragsbild-e1368539786361.jpg\",\"width\":200,\"height\":133},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/4-park-guell-und-berg-tibidabo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reiseberichte\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Europa\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"2013 Spanien - Barcelona\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"4. Park G\u00fcell und Berg Tibidabo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#website\",\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/\",\"name\":\"Reiseberichte\",\"description\":\"In der Welt zu Hause\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#\\\/schema\\\/person\\\/5c31a83093ce724f3bf8ae666747d594\",\"name\":\"Chris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g\",\"caption\":\"Chris\"},\"sameAs\":[\"https:\\\/\\\/familie-papp.de\",\"https:\\\/\\\/x.com\\\/chris_papp_de\"],\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/author\\\/chris\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4. Park G\u00fcell und Berg Tibidabo - Reiseberichte","description":"An unserem letzten Tag haben wir den Park G\u00fcell und den Hausberg von Barcelona Tibidabo und die Kirche Sagrat Cor besichtigt. Um den Parc G\u00fcell zu sehen, lohnt es sich an der Metrostation Vallcarca auszusteigen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/","og_locale":"de_DE","og_type":"article","og_title":"4. Park G\u00fcell und Berg Tibidabo - Reiseberichte","og_description":"An unserem letzten Tag haben wir den Park G\u00fcell und den Hausberg von Barcelona Tibidabo und die Kirche Sagrat Cor besichtigt. Um den Parc G\u00fcell zu sehen, lohnt es sich an der Metrostation Vallcarca auszusteigen.","og_url":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/","og_site_name":"Reiseberichte","article_published_time":"2013-05-14T13:55:16+00:00","article_modified_time":"2020-08-03T11:14:42+00:00","og_image":[{"width":200,"height":133,"url":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2013-barcelona-4-tibidabo-Beitragsbild-e1368539786361.jpg","type":"image\/jpeg"}],"author":"Chris","twitter_card":"summary_large_image","twitter_creator":"@chris_papp_de","twitter_site":"@chris_papp_de","twitter_misc":{"Verfasst von":"Chris","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/#article","isPartOf":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/"},"author":{"name":"Chris","@id":"https:\/\/www.familie-papp.de\/reisen\/#\/schema\/person\/5c31a83093ce724f3bf8ae666747d594"},"headline":"4. Park G\u00fcell und Berg Tibidabo","datePublished":"2013-05-14T13:55:16+00:00","dateModified":"2020-08-03T11:14:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/"},"wordCount":445,"commentCount":0,"image":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2013-barcelona-4-tibidabo-Beitragsbild-e1368539786361.jpg","articleSection":["2013 Spanien - Barcelona"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/","url":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/","name":"4. Park G\u00fcell und Berg Tibidabo - Reiseberichte","isPartOf":{"@id":"https:\/\/www.familie-papp.de\/reisen\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/#primaryimage"},"image":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2013-barcelona-4-tibidabo-Beitragsbild-e1368539786361.jpg","datePublished":"2013-05-14T13:55:16+00:00","dateModified":"2020-08-03T11:14:42+00:00","author":{"@id":"https:\/\/www.familie-papp.de\/reisen\/#\/schema\/person\/5c31a83093ce724f3bf8ae666747d594"},"description":"An unserem letzten Tag haben wir den Park G\u00fcell und den Hausberg von Barcelona Tibidabo und die Kirche Sagrat Cor besichtigt. Um den Parc G\u00fcell zu sehen, lohnt es sich an der Metrostation Vallcarca auszusteigen.","breadcrumb":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/#primaryimage","url":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2013-barcelona-4-tibidabo-Beitragsbild-e1368539786361.jpg","contentUrl":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2013-barcelona-4-tibidabo-Beitragsbild-e1368539786361.jpg","width":200,"height":133},{"@type":"BreadcrumbList","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/4-park-guell-und-berg-tibidabo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.familie-papp.de\/reisen\/"},{"@type":"ListItem","position":2,"name":"Reiseberichte","item":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/"},{"@type":"ListItem","position":3,"name":"Europa","item":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/"},{"@type":"ListItem","position":4,"name":"2013 Spanien - Barcelona","item":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/"},{"@type":"ListItem","position":5,"name":"4. Park G\u00fcell und Berg Tibidabo"}]},{"@type":"WebSite","@id":"https:\/\/www.familie-papp.de\/reisen\/#website","url":"https:\/\/www.familie-papp.de\/reisen\/","name":"Reiseberichte","description":"In der Welt zu Hause","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.familie-papp.de\/reisen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.familie-papp.de\/reisen\/#\/schema\/person\/5c31a83093ce724f3bf8ae666747d594","name":"Chris","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g","caption":"Chris"},"sameAs":["https:\/\/familie-papp.de","https:\/\/x.com\/chris_papp_de"],"url":"https:\/\/www.familie-papp.de\/reisen\/author\/chris\/"}]}},"_links":{"self":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts\/241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/comments?post=241"}],"version-history":[{"count":11,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts\/241\/revisions"}],"predecessor-version":[{"id":2268,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts\/241\/revisions\/2268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/media\/243"}],"wp:attachment":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/media?parent=241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/categories?post=241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/tags?post=241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}