{"id":345,"date":"2013-05-19T21:59:05","date_gmt":"2013-05-19T19:59:05","guid":{"rendered":"https:\/\/www.familie-papp.de\/reisen\/?p=345"},"modified":"2019-05-07T12:03:26","modified_gmt":"2019-05-07T10:03:26","slug":"2013-barcelona-uebersicht-reiseverlauf","status":"publish","type":"post","link":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/","title":{"rendered":"2013 Barcelona &#8211; \u00dcbersicht \u00fcber den Reiseverlauf"},"content":{"rendered":"<table border=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td><a title=\"Reiseberichte\" href=\"https:\/\/www.familie-papp.de\/reisen\/uebersicht-reiseberichte\/\">Alle Reiseberichte<\/a><\/td>\n<td><\/td>\n<td style=\"text-align: right;\"><a title=\"1. Anreise nach Barcelona und Sagrada Familia\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-barcelona\/1-anreise-nach-barcelona-und-sagrada-familia\/\">Weiter\u00a0\u203a<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Karte<\/h3>\n\n<p><span style=\"font-size: 22px; font-weight: bold;\">Reisedetails<\/span><\/p>\n<p><strong>Datum: <\/strong>08.05.-12.05.2013<br \/>\n<strong>Startpunkt:<\/strong> Barcelona, Spanien<br \/>\n<strong>Endpunkt:<\/strong> Barcelona, Spanien<\/p>\n<h3>Verlauf<\/h3>\n<table style=\"width: 100%;\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"84\" \/>\n<col width=\"133\" \/>\n<col width=\"92\" \/><\/colgroup>\n<tbody>\n<tr>\n<td width=\"84\" height=\"20\"><strong>Datum<\/strong><\/td>\n<td style=\"text-align: left;\" width=\"92\"><strong>Beschreibung<\/strong><\/td>\n<td style=\"text-align: right;\" width=\"92\"><strong>Reisebericht<\/strong><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">08.05.2013<\/td>\n<td align=\"right\">Ankunft<\/td>\n<td align=\"right\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td align=\"right\">Die Kirche Sagrada Fam\u00edlia<\/td>\n<td align=\"right\"><a title=\"1. Anreise nach Barcelona und Sagrada Familia\" href=\"https:\/\/www.familie-papp.de\/reisen\/europa\/2013-barcelona\/1-anreise-nach-barcelona-und-sagrada-familia\/\">1. Anreise nach Barcelona und Sagrada Familia<\/a><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td align=\"right\"><\/td>\n<td align=\"right\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">09.05.2013<\/td>\n<td align=\"right\">Gotisches Viertel<\/td>\n<td align=\"right\"><a title=\"2. Gotisches Viertel, Rambla, Placa del Rei, Aquarium\" href=\"https:\/\/www.familie-papp.de\/reisen\/europa\/2013-barcelona\/2-gotisches-viertel-rambla-placa-del-rei-aquarium\/\">2. Gotisches Viertel, Rambla, Montjuic, Aquarium<\/a><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td align=\"right\">Rambla<\/td>\n<td align=\"right\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td align=\"right\">Montju\u00efc<\/td>\n<td align=\"right\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td align=\"right\">Las Golondrians &#8211; Hafenrundfahrt<\/td>\n<td align=\"right\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td align=\"right\">L&#8216; Aquatrium<\/td>\n<td align=\"right\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td align=\"right\"><\/td>\n<td align=\"right\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">10.05.2013<\/td>\n<td align=\"right\">Parc de la Ciutadella<\/td>\n<td align=\"right\"><a title=\"3. Parc de la Ciutadella, Catedral, Arc de Triomf\" href=\"https:\/\/www.familie-papp.de\/reisen\/europa\/2013-barcelona\/3-parc-de-la-ciutadella-catedral-arc-de-triomf\/\">3. Parc de la Ciutadella, Catedral, Arc de Triomf<\/a><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td align=\"right\">Stadtgeschichte Museum<\/td>\n<td align=\"right\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td align=\"right\">Catedral<\/td>\n<td align=\"right\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td align=\"right\">Piccaso Museum<\/td>\n<td align=\"right\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td align=\"right\">Placa del Rei<\/td>\n<td align=\"right\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td align=\"right\"><\/td>\n<td align=\"right\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">11.05.2013<\/td>\n<td align=\"right\">Parc G\u00fcell<\/td>\n<td align=\"right\"><a title=\"4. Park G\u00fcell und Berg Tibidabo\" href=\"https:\/\/www.familie-papp.de\/reisen\/europa\/2013-barcelona\/4-park-guell-und-berg-tibidabo\/\">4. Park G\u00fcell und Berg Tibidabo<\/a><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td align=\"right\">Berg Tibidabo<\/td>\n<td align=\"right\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td align=\"right\"><\/td>\n<td align=\"right\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">12.05.2013<\/td>\n<td align=\"right\">R\u00fcckflug<\/td>\n<td align=\"right\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table border=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td><a title=\"Reiseberichte\" href=\"https:\/\/www.familie-papp.de\/reisen\/uebersicht-reiseberichte\/\">Alle Reiseberichte<\/a><\/td>\n<td><\/td>\n<td style=\"text-align: right;\"><a title=\"1. Anreise nach Barcelona und Sagrada Familia\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-barcelona\/1-anreise-nach-barcelona-und-sagrada-familia\/\">Weiter\u00a0\u203a<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Datum: 08.05.-12.05.2013<br \/>\nStartpunkt: Barcelona Airport, Spanien<br \/>\nEndpunkt: Barcelona Airport, Spanien<br \/>\n <a class=\"more-link\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/\"><span class=\"screen-reader-text\">  2013 Barcelona &#8211; \u00dcbersicht \u00fcber den Reiseverlauf<\/span> weiterlesen<span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":369,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2013-spanien-barcelona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2013 Barcelona - \u00dcbersicht \u00fcber den Reiseverlauf - Reiseberichte<\/title>\n<meta name=\"description\" content=\"Auf dieser Webseite findest du pers\u00f6nliche Reiseberichte unserer Reisen. 2012 USA Westk\u00fcste, 2011 USA Ostk\u00fcste, 2013 Barcelona und viele mehr...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2013 Barcelona - \u00dcbersicht \u00fcber den Reiseverlauf - Reiseberichte\" \/>\n<meta property=\"og:description\" content=\"Auf dieser Webseite findest du pers\u00f6nliche Reiseberichte unserer Reisen. 2012 USA Westk\u00fcste, 2011 USA Ostk\u00fcste, 2013 Barcelona und viele mehr...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/\" \/>\n<meta property=\"og:site_name\" content=\"Reiseberichte\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-19T19:59:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-07T10:03:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2013-Barcelona-Beitragsbild-e1369571503154.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"237\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@chris_papp_de\" \/>\n<meta name=\"twitter:site\" content=\"@chris_papp_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chris\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/2013-barcelona-uebersicht-reiseverlauf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/2013-barcelona-uebersicht-reiseverlauf\\\/\"},\"author\":{\"name\":\"Chris\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#\\\/schema\\\/person\\\/5c31a83093ce724f3bf8ae666747d594\"},\"headline\":\"2013 Barcelona &#8211; \u00dcbersicht \u00fcber den Reiseverlauf\",\"datePublished\":\"2013-05-19T19:59:05+00:00\",\"dateModified\":\"2019-05-07T10:03:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/2013-barcelona-uebersicht-reiseverlauf\\\/\"},\"wordCount\":89,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/2013-barcelona-uebersicht-reiseverlauf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2013-Barcelona-Beitragsbild-e1369571503154.jpg\",\"articleSection\":[\"2013 Spanien - Barcelona\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/2013-barcelona-uebersicht-reiseverlauf\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/2013-barcelona-uebersicht-reiseverlauf\\\/\",\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/2013-barcelona-uebersicht-reiseverlauf\\\/\",\"name\":\"2013 Barcelona - \u00dcbersicht \u00fcber den Reiseverlauf - Reiseberichte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/2013-barcelona-uebersicht-reiseverlauf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/2013-barcelona-uebersicht-reiseverlauf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2013-Barcelona-Beitragsbild-e1369571503154.jpg\",\"datePublished\":\"2013-05-19T19:59:05+00:00\",\"dateModified\":\"2019-05-07T10:03:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#\\\/schema\\\/person\\\/5c31a83093ce724f3bf8ae666747d594\"},\"description\":\"Auf dieser Webseite findest du pers\u00f6nliche Reiseberichte unserer Reisen. 2012 USA Westk\u00fcste, 2011 USA Ostk\u00fcste, 2013 Barcelona und viele mehr...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/2013-barcelona-uebersicht-reiseverlauf\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/2013-barcelona-uebersicht-reiseverlauf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/2013-barcelona-uebersicht-reiseverlauf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2013-Barcelona-Beitragsbild-e1369571503154.jpg\",\"contentUrl\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2013-Barcelona-Beitragsbild-e1369571503154.jpg\",\"width\":237,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/2013-barcelona-uebersicht-reiseverlauf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reiseberichte\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Europa\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"2013 Spanien - Barcelona\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/europa\\\/2013-spanien-barcelona\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"2013 Barcelona &#8211; \u00dcbersicht \u00fcber den Reiseverlauf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#website\",\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/\",\"name\":\"Reiseberichte\",\"description\":\"In der Welt zu Hause\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#\\\/schema\\\/person\\\/5c31a83093ce724f3bf8ae666747d594\",\"name\":\"Chris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g\",\"caption\":\"Chris\"},\"sameAs\":[\"https:\\\/\\\/familie-papp.de\",\"https:\\\/\\\/x.com\\\/chris_papp_de\"],\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/author\\\/chris\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2013 Barcelona - \u00dcbersicht \u00fcber den Reiseverlauf - Reiseberichte","description":"Auf dieser Webseite findest du pers\u00f6nliche Reiseberichte unserer Reisen. 2012 USA Westk\u00fcste, 2011 USA Ostk\u00fcste, 2013 Barcelona und viele mehr...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/","og_locale":"de_DE","og_type":"article","og_title":"2013 Barcelona - \u00dcbersicht \u00fcber den Reiseverlauf - Reiseberichte","og_description":"Auf dieser Webseite findest du pers\u00f6nliche Reiseberichte unserer Reisen. 2012 USA Westk\u00fcste, 2011 USA Ostk\u00fcste, 2013 Barcelona und viele mehr...","og_url":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/","og_site_name":"Reiseberichte","article_published_time":"2013-05-19T19:59:05+00:00","article_modified_time":"2019-05-07T10:03:26+00:00","og_image":[{"width":237,"height":200,"url":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2013-Barcelona-Beitragsbild-e1369571503154.jpg","type":"image\/jpeg"}],"author":"Chris","twitter_card":"summary_large_image","twitter_creator":"@chris_papp_de","twitter_site":"@chris_papp_de","twitter_misc":{"Verfasst von":"Chris"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/#article","isPartOf":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/"},"author":{"name":"Chris","@id":"https:\/\/www.familie-papp.de\/reisen\/#\/schema\/person\/5c31a83093ce724f3bf8ae666747d594"},"headline":"2013 Barcelona &#8211; \u00dcbersicht \u00fcber den Reiseverlauf","datePublished":"2013-05-19T19:59:05+00:00","dateModified":"2019-05-07T10:03:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/"},"wordCount":89,"commentCount":0,"image":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2013-Barcelona-Beitragsbild-e1369571503154.jpg","articleSection":["2013 Spanien - Barcelona"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/","url":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/","name":"2013 Barcelona - \u00dcbersicht \u00fcber den Reiseverlauf - Reiseberichte","isPartOf":{"@id":"https:\/\/www.familie-papp.de\/reisen\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/#primaryimage"},"image":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2013-Barcelona-Beitragsbild-e1369571503154.jpg","datePublished":"2013-05-19T19:59:05+00:00","dateModified":"2019-05-07T10:03:26+00:00","author":{"@id":"https:\/\/www.familie-papp.de\/reisen\/#\/schema\/person\/5c31a83093ce724f3bf8ae666747d594"},"description":"Auf dieser Webseite findest du pers\u00f6nliche Reiseberichte unserer Reisen. 2012 USA Westk\u00fcste, 2011 USA Ostk\u00fcste, 2013 Barcelona und viele mehr...","breadcrumb":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/#primaryimage","url":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2013-Barcelona-Beitragsbild-e1369571503154.jpg","contentUrl":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2013-Barcelona-Beitragsbild-e1369571503154.jpg","width":237,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/2013-barcelona-uebersicht-reiseverlauf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.familie-papp.de\/reisen\/"},{"@type":"ListItem","position":2,"name":"Reiseberichte","item":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/"},{"@type":"ListItem","position":3,"name":"Europa","item":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/"},{"@type":"ListItem","position":4,"name":"2013 Spanien - Barcelona","item":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/europa\/2013-spanien-barcelona\/"},{"@type":"ListItem","position":5,"name":"2013 Barcelona &#8211; \u00dcbersicht \u00fcber den Reiseverlauf"}]},{"@type":"WebSite","@id":"https:\/\/www.familie-papp.de\/reisen\/#website","url":"https:\/\/www.familie-papp.de\/reisen\/","name":"Reiseberichte","description":"In der Welt zu Hause","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.familie-papp.de\/reisen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.familie-papp.de\/reisen\/#\/schema\/person\/5c31a83093ce724f3bf8ae666747d594","name":"Chris","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g","caption":"Chris"},"sameAs":["https:\/\/familie-papp.de","https:\/\/x.com\/chris_papp_de"],"url":"https:\/\/www.familie-papp.de\/reisen\/author\/chris\/"}]}},"_links":{"self":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts\/345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/comments?post=345"}],"version-history":[{"count":9,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts\/345\/revisions"}],"predecessor-version":[{"id":2178,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts\/345\/revisions\/2178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/media\/369"}],"wp:attachment":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/media?parent=345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/categories?post=345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/tags?post=345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}