{"id":4,"date":"2013-05-05T18:40:29","date_gmt":"2013-05-05T16:40:29","guid":{"rendered":"https:\/\/www.familie-papp.de\/reiseberichte\/?p=4"},"modified":"2020-08-03T10:55:33","modified_gmt":"2020-08-03T08:55:33","slug":"anreise-nach-san-francisco","status":"publish","type":"post","link":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/","title":{"rendered":"1. Anreise nach San Francisco"},"content":{"rendered":"<table border=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td style=\"text-align: left;\"><a title=\"2012 USA West \u2013 \u00dcbersicht \u00fcber den Reiseverlauf\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/2012-usa-west-uebersicht-reiseverlauf\/\">\u2039\u00a0Zur\u00fcck<\/a><\/td>\n<td style=\"text-align: center;\"><a title=\"2012 USA West \u2013 \u00dcbersicht \u00fcber den Reiseverlauf\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/2012-usa-west-uebersicht-reiseverlauf\/\">Reiseverlauf<\/a><\/td>\n<td style=\"text-align: right;\"><a title=\"2. Highway 1 und Monterey\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/highway-1-und-monterey\/\">Weiter \u00a0\u203a<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: left;\">ngg_shortcode_0_placeholder Unsere 4000 km lange Reise beginnt am 09.07.2012\u00a0in der Hauptstadt Karliforniens, San Francisco. Sie ist mit eine der sch\u00f6nsten St\u00e4dte der USA und bietet f\u00fcr jeden etwas, Natur, kulinarische Gen\u00fcsse und Kultur. Leider hatten wir hier nur einen Tag, den wir genutzt haben, um von Pier Nr. 1, dem <a title=\"Ferry Building\" href=\"https:\/\/www.familie-papp.de\/reisen\/wp-content\/gallery\/2012_usa-west-1\/2012-usa-west-002.jpg\">Ferry Building<\/a> einmal um die Spitze der Halbinsel bis zur <a title=\"Golden Gate Bridge\" href=\"https:\/\/www.familie-papp.de\/reisen\/wp-content\/gallery\/2012_usa-west-1\/2012-usa-west-023.jpg\">Golden Gate Bridge<\/a> zu Wandern.<\/p>\n<p style=\"text-align: left;\">ngg_shortcode_1_placeholder Immer an der K\u00fcste entlang mit wechselnden\u00a0Blick auf die\u00a0ber\u00fchmteste\u00a0Gef\u00e4ngnisinsel der Welt <a title=\"Alcatraz\" href=\"https:\/\/www.familie-papp.de\/reisen\/wp-content\/gallery\/2012_usa-west-1\/2012-usa-west-010.jpg\">Alcatraz<\/a>. Falls man diese besuchen m\u00f6chte, muss man leider mindestens drei Wochen vorher reservieren. Der Pier, von dem aus die Touristenf\u00e4hren zur Insel ablegen, bietet ein kleines Museum \u00fcber die Geschichte der Insel und deren, nicht nur ber\u00fchmte und straff\u00e4llige Bewohner, sondern auch \u00fcber die ganz normalen Menschen und die Familien des Gef\u00e4ngnispersonals.<\/p>\n<p style=\"text-align: left;\">ngg_shortcode_2_placeholder Auf dem weiteren Weg sind wir an an <a title=\"Pier 39\" href=\"https:\/\/www.familie-papp.de\/reisen\/wp-content\/gallery\/2012_usa-west-1\/2012-usa-west-012.jpg\">Pier 39<\/a>\u00a0vorbei gekommen, wo sich das ber\u00fchmte Aquarium\u00a0Aquatic Park mit einem Unterwassertunnel und faszinierenden Einblicken in die Unterwasserwelt der San\u00a0Francisco\u00a0Bucht befindet und viele kleine L\u00e4den und Restaurants. Von hier aus haben wir eine mini\u00a0Schiffsrundfahrt zu\u00a0Alcatraz und stillgelegten Kriegsschiffen gemacht. Wir wollten auch die ber\u00fchmte Seehund-Kolonie bestaunen, leider waren wir zu fr\u00fch im Jahr, so dass bis auf ein einsames Tier, welches wohl die Stellung gehalten hat, keine Seehunde da waren. Erst ab August, so informierte uns eine Infotafel, wimmelt es hier nur so von Seehunden, wie man es von Bildern aus San Francisco\u00a0kennt. Weiter ging\u00b4s zum <a title=\"Hide Street Pier\" href=\"https:\/\/www.familie-papp.de\/reisen\/wp-content\/gallery\/2012_usa-west-1\/2012-usa-west-017.jpg\">Hide Street Pier<\/a>, hier kann man ein\u00a0Museum\u00a0mit alten Schiffen besichtigen.<\/p>\n<p style=\"text-align: left;\">ngg_shortcode_3_placeholder Fishermans Wharf bietet viele kulinarische Gen\u00fcsse und allerhand\u00a0skurrile\u00a0Gestalten, K\u00fcnstler und Selbstdarsteller, die auf ein paar Touristendoller hoffen. Letzte Station und somit fast am Ziel der Wanderung, war <a title=\"Fort Point\" href=\"https:\/\/www.familie-papp.de\/reisen\/wp-content\/gallery\/2012_usa-west-1\/2012-usa-west-025.jpg\">Fort Point<\/a> direkt unter der Golden Gate,\u00a0eines der ersten Milit\u00e4rgeb\u00e4ude im amerikanischen Westen und heute ein Museum, welches auch die Geschichte der Golden Gate Bridge erz\u00e4hlt. Auf Grund ihrer besonderen Lage ist die Golden Gate oft in einem undurchdringlichen Nebel verborgen, so dass sch\u00f6ne Fotos auch f\u00fcr uns leider an diesem Tag nicht machbar waren. Was wir auf unserer kleinen Wanderung sehr untersch\u00e4tzt haben, nicht zuletzt durch den permanenten k\u00fchlen Wind vom Meer her, war die Sonne Kaliforniens. Trotz das es zum Teil regelrecht kalt war, eine leichte Jacke, die den Wind abh\u00e4lt, ist dringend zu empfehlen, haben wir uns einen ordentlichen Sonnenbrand eingeholt.<\/p>\n<p style=\"text-align: left;\">ngg_shortcode_4_placeholder Von der Golden Gate Bridge haben wir einen normalen Linienbus zur\u00fcck zur Stadt genommen und sind an der oberen Station der ber\u00fchmten <a title=\"Cable Cars\" href=\"https:\/\/www.familie-papp.de\/reisen\/wp-content\/gallery\/2012_usa-west-1\/2012-usa-west-027.jpg\">Cable Cars<\/a>, zugestiegen und h\u00fcgelabw\u00e4rts zur <a title=\"Powell Street\" href=\"https:\/\/www.familie-papp.de\/reisen\/wp-content\/gallery\/2012_usa-west-1\/2012-usa-west-029.jpg\">Powell Street<\/a> gefahren, ein einmaliges Erlebnis ohne das kein Besuch der Stadt vollst\u00e4ndig ist. Dadurch, dass wir oben eingestiegen sind, war die Bahn fast komplett leer, so dass wir freie Platzwahl hatten und ganz vorne sitzen konnten. An unserem zweiten Tag haben wir vor unserer Weiterreise noch den ber\u00fchmten\u00a0<a title=\"Union Square\" href=\"https:\/\/www.familie-papp.de\/reisen\/wp-content\/gallery\/2012_usa-west-1\/2012-usa-west-030.jpg\">Union Square<\/a> besichtigt und in der Burger Bar im\u00a0Macy\u2019s bei fantastischer Aussicht auf den Platz gespeist. Bevor es zur n\u00e4chsten Station auf unserer Reise ging.<\/p>\n<h3>Bilder<\/h3>\nngg_shortcode_5_placeholder\n<h3><span style=\"font-size: 1.17em;\">Karte<\/span><\/h3>\n\n<table border=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td style=\"text-align: left;\"><a title=\"2012 USA West \u2013 \u00dcbersicht \u00fcber den Reiseverlauf\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/2012-usa-west-uebersicht-reiseverlauf\/\">\u2039\u00a0Zur\u00fcck<\/a><\/td>\n<td style=\"text-align: center;\"><a title=\"2012 USA West \u2013 \u00dcbersicht \u00fcber den Reiseverlauf\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/2012-usa-west-uebersicht-reiseverlauf\/\">Reiseverlauf<\/a><\/td>\n<td style=\"text-align: right;\"><a title=\"2. Highway 1 und Monterey\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/highway-1-und-monterey\/\">Weiter \u00a0\u203a<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Unsere 4000 km lange Reise beginnt am 09.07.2012 in der Hauptstadt Karliforniens, San Francisco. Sie ist mit eine der sch\u00f6nsten St\u00e4dte der USA und bietet f\u00fcr jeden etwas, Natur, kulinarische Gen\u00fcsse und Kultur.<br \/>\n <a class=\"more-link\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/\"><span class=\"screen-reader-text\">  1. Anreise nach San Francisco<\/span> weiterlesen<span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":93,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2012-usa-westkueste"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1. Anreise nach San Francisco - Reiseberichte<\/title>\n<meta name=\"description\" content=\"Unsere 4000 km lange Reise beginnt am 09.07.2012 in der Hauptstadt Karliforniens, San Francisco. Sie ist mit eine der sch\u00f6nsten St\u00e4dte der USA und bietet f\u00fcr jeden etwas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1. Anreise nach San Francisco - Reiseberichte\" \/>\n<meta property=\"og:description\" content=\"Unsere 4000 km lange Reise beginnt am 09.07.2012 in der Hauptstadt Karliforniens, San Francisco. Sie ist mit eine der sch\u00f6nsten St\u00e4dte der USA und bietet f\u00fcr jeden etwas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/\" \/>\n<meta property=\"og:site_name\" content=\"Reiseberichte\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-05T16:40:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-03T08:55:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2012-USA-West-Anreise-Beitragsbild-e1369660351240.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"427\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@chris_papp_de\" \/>\n<meta name=\"twitter:site\" content=\"@chris_papp_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chris\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2012-usa-westkueste\\\/anreise-nach-san-francisco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2012-usa-westkueste\\\/anreise-nach-san-francisco\\\/\"},\"author\":{\"name\":\"Chris\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#\\\/schema\\\/person\\\/5c31a83093ce724f3bf8ae666747d594\"},\"headline\":\"1. Anreise nach San Francisco\",\"datePublished\":\"2013-05-05T16:40:29+00:00\",\"dateModified\":\"2020-08-03T08:55:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2012-usa-westkueste\\\/anreise-nach-san-francisco\\\/\"},\"wordCount\":571,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2012-usa-westkueste\\\/anreise-nach-san-francisco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2012-USA-West-Anreise-Beitragsbild-e1369660351240.jpg\",\"articleSection\":[\"2012 USA Westk\u00fcste\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2012-usa-westkueste\\\/anreise-nach-san-francisco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2012-usa-westkueste\\\/anreise-nach-san-francisco\\\/\",\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2012-usa-westkueste\\\/anreise-nach-san-francisco\\\/\",\"name\":\"1. Anreise nach San Francisco - Reiseberichte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2012-usa-westkueste\\\/anreise-nach-san-francisco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2012-usa-westkueste\\\/anreise-nach-san-francisco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2012-USA-West-Anreise-Beitragsbild-e1369660351240.jpg\",\"datePublished\":\"2013-05-05T16:40:29+00:00\",\"dateModified\":\"2020-08-03T08:55:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#\\\/schema\\\/person\\\/5c31a83093ce724f3bf8ae666747d594\"},\"description\":\"Unsere 4000 km lange Reise beginnt am 09.07.2012 in der Hauptstadt Karliforniens, San Francisco. Sie ist mit eine der sch\u00f6nsten St\u00e4dte der USA und bietet f\u00fcr jeden etwas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2012-usa-westkueste\\\/anreise-nach-san-francisco\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2012-usa-westkueste\\\/anreise-nach-san-francisco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2012-usa-westkueste\\\/anreise-nach-san-francisco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2012-USA-West-Anreise-Beitragsbild-e1369660351240.jpg\",\"contentUrl\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2012-USA-West-Anreise-Beitragsbild-e1369660351240.jpg\",\"width\":427,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2012-usa-westkueste\\\/anreise-nach-san-francisco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reiseberichte\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Amerika\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"2012 USA Westk\u00fcste\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2012-usa-westkueste\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"1. Anreise nach San Francisco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#website\",\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/\",\"name\":\"Reiseberichte\",\"description\":\"In der Welt zu Hause\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#\\\/schema\\\/person\\\/5c31a83093ce724f3bf8ae666747d594\",\"name\":\"Chris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g\",\"caption\":\"Chris\"},\"sameAs\":[\"https:\\\/\\\/familie-papp.de\",\"https:\\\/\\\/x.com\\\/chris_papp_de\"],\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/author\\\/chris\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1. Anreise nach San Francisco - Reiseberichte","description":"Unsere 4000 km lange Reise beginnt am 09.07.2012 in der Hauptstadt Karliforniens, San Francisco. Sie ist mit eine der sch\u00f6nsten St\u00e4dte der USA und bietet f\u00fcr jeden etwas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/","og_locale":"de_DE","og_type":"article","og_title":"1. Anreise nach San Francisco - Reiseberichte","og_description":"Unsere 4000 km lange Reise beginnt am 09.07.2012 in der Hauptstadt Karliforniens, San Francisco. Sie ist mit eine der sch\u00f6nsten St\u00e4dte der USA und bietet f\u00fcr jeden etwas.","og_url":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/","og_site_name":"Reiseberichte","article_published_time":"2013-05-05T16:40:29+00:00","article_modified_time":"2020-08-03T08:55:33+00:00","og_image":[{"width":427,"height":320,"url":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2012-USA-West-Anreise-Beitragsbild-e1369660351240.jpg","type":"image\/jpeg"}],"author":"Chris","twitter_card":"summary_large_image","twitter_creator":"@chris_papp_de","twitter_site":"@chris_papp_de","twitter_misc":{"Verfasst von":"Chris","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/#article","isPartOf":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/"},"author":{"name":"Chris","@id":"https:\/\/www.familie-papp.de\/reisen\/#\/schema\/person\/5c31a83093ce724f3bf8ae666747d594"},"headline":"1. Anreise nach San Francisco","datePublished":"2013-05-05T16:40:29+00:00","dateModified":"2020-08-03T08:55:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/"},"wordCount":571,"commentCount":0,"image":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2012-USA-West-Anreise-Beitragsbild-e1369660351240.jpg","articleSection":["2012 USA Westk\u00fcste"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/","url":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/","name":"1. Anreise nach San Francisco - Reiseberichte","isPartOf":{"@id":"https:\/\/www.familie-papp.de\/reisen\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/#primaryimage"},"image":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2012-USA-West-Anreise-Beitragsbild-e1369660351240.jpg","datePublished":"2013-05-05T16:40:29+00:00","dateModified":"2020-08-03T08:55:33+00:00","author":{"@id":"https:\/\/www.familie-papp.de\/reisen\/#\/schema\/person\/5c31a83093ce724f3bf8ae666747d594"},"description":"Unsere 4000 km lange Reise beginnt am 09.07.2012 in der Hauptstadt Karliforniens, San Francisco. Sie ist mit eine der sch\u00f6nsten St\u00e4dte der USA und bietet f\u00fcr jeden etwas.","breadcrumb":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/#primaryimage","url":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2012-USA-West-Anreise-Beitragsbild-e1369660351240.jpg","contentUrl":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2012-USA-West-Anreise-Beitragsbild-e1369660351240.jpg","width":427,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/anreise-nach-san-francisco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.familie-papp.de\/reisen\/"},{"@type":"ListItem","position":2,"name":"Reiseberichte","item":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/"},{"@type":"ListItem","position":3,"name":"Amerika","item":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/"},{"@type":"ListItem","position":4,"name":"2012 USA Westk\u00fcste","item":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2012-usa-westkueste\/"},{"@type":"ListItem","position":5,"name":"1. Anreise nach San Francisco"}]},{"@type":"WebSite","@id":"https:\/\/www.familie-papp.de\/reisen\/#website","url":"https:\/\/www.familie-papp.de\/reisen\/","name":"Reiseberichte","description":"In der Welt zu Hause","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.familie-papp.de\/reisen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.familie-papp.de\/reisen\/#\/schema\/person\/5c31a83093ce724f3bf8ae666747d594","name":"Chris","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g","caption":"Chris"},"sameAs":["https:\/\/familie-papp.de","https:\/\/x.com\/chris_papp_de"],"url":"https:\/\/www.familie-papp.de\/reisen\/author\/chris\/"}]}},"_links":{"self":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/comments?post=4"}],"version-history":[{"count":9,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts\/4\/revisions"}],"predecessor-version":[{"id":2208,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts\/4\/revisions\/2208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/media\/93"}],"wp:attachment":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/media?parent=4"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/categories?post=4"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/tags?post=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}