{"id":589,"date":"2013-05-25T17:10:12","date_gmt":"2013-05-25T15:10:12","guid":{"rendered":"https:\/\/www.familie-papp.de\/reisen\/?p=589"},"modified":"2020-08-03T10:29:19","modified_gmt":"2020-08-03T08:29:19","slug":"2-newport-und-plymouth","status":"publish","type":"post","link":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/","title":{"rendered":"2. Newport und Plymouth"},"content":{"rendered":"<table border=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td style=\"text-align: left;\"><a title=\"1. Anreise nach New York\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/1-anreise-nach-new-york\/\">\u2039\u00a0Zur\u00fcck<\/a><\/td>\n<td style=\"text-align: center;\"><a title=\"2011 USA Ost \u2013 \u00dcbersicht \u00fcber den Reiseverlauf\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2011-usa-ost-uebersicht-reiseverlauf\/\">Reiseverlauf<\/a><\/td>\n<td style=\"text-align: right;\"><a title=\"3. Boston\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/3-boston\/\">Weiter \u00a0\u203a<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>ngg_shortcode_0_placeholder Nach unserem Aufenthalt in New York sind wir weiter an der K\u00fcste entlang zum kleinen \u00d6rtchen Newport gefahren. Das \u00d6rtchen besticht durch seinen sch\u00f6n angelegten Hafen mit vielen Restaurants und Gesch\u00e4ften, leider war das Wetter nicht so sch\u00f6n, von daher haben wir beschlossen weiter zu fahren. Wir hatten unsere weiteren Hotels nicht vorgebucht, um flexibel zu bleiben. Es gibt sehr viele Hotels der bekannten Hotelketten an der Ostk\u00fcste. Teurer, aber daf\u00fcr von der Qualit\u00e4t und dem Ambiente immer top waren die Best Western Hotels. G\u00fcnstiger, aber nicht ganz so topp, je nach dem unter welchem Management gef\u00fchrt, waren Super 6 und Super 8.\u00a0Hier waren Qualit\u00e4t und Zimmer nicht immer gleich. Immer gut war ein Besuch im Tourism-Center der Stadt, die meisten gr\u00f6\u00dferen St\u00e4dte haben eins. Hier sitzen meist freundliche \u00e4ltere Damen, mit einem Verzeichnis der Hotels vor Ort und Tipps, welche Hotels g\u00fcnstig sind, meistens kann man von dort auch kostenlos anrufen und fragen, ob etwas frei ist und was es kostet. Das erspart einem das nervige Umherfahren und Suchen. In Plymouth haben wir einmal auch eine kleine Pension, Blue Anchor, in einem umgebauten Wohnhaus vermittelt bekommen, was sehr interessant war und gem\u00fctlicher, als die immer gleichen unpers\u00f6nlichen Hotels. Auf gutes Fr\u00fchst\u00fcck darf man bei den Amerikanern selten hoffen.\u00a0Wenn man gut fr\u00fchst\u00fccken m\u00f6chte, muss man in ein Diner gehen. Genau das haben wir auch in Plymuoth gemacht und klassisch Toast, Eier mit Speck und Kaffee genossen. Danach haben wir uns das Museumsschiff, die nachgebaute Mayflower II angeschaut und einen Gedenkstein, da hier die ersten Einwanderer in die USA ihren Fu\u00df auf den Boden gesetzt haben.<\/p>\n<p>ngg_shortcode_1_placeholder Was man unbedingt gemacht haben sollte, vorausgesetzt man mag Meerestiere, ist Lobster essen. Aber es lohnt sich daf\u00fcr die Touristenmeile, meist rund um den Hafen, zu verlassen. Hier bekommt man n\u00e4mlich ein einfaches Hummermen\u00fc f\u00fcr rund 40 $ pro Person und dabei sind meist nur ein Salatblatt als Beilage und das sch\u00f6ne Ambiente des Restaurants.\u00a0Wir sind ein St\u00fcck am Hafen entlang gelaufen und im Lobster Hut (25 Town Wharf, Plymouth, MA),\u00a0einer Art &#8222;Lobster-Bude&#8220;, gelandet. Hier essen die Einheimischen, die die \u00fcberteuerten Touristenpreise nicht zahlen wollen und das einfache Lobstermen\u00fc kostet ca. 12 $ pro Person. Man bekommt eine Portion Pommes und ein Sch\u00e4lchen mit Krautsalat dazu, stilecht vom Plastikgeschirr mit Plastikl\u00e4tzchen. Das, was man vom Hummer letztendlich essen kann, ist so wenig, dass man sich bei 40 $ ge\u00e4rgert h\u00e4tte. Au\u00dferdem helfen einem die Einheimischen gern beim Essen von so einem Viech, das ist n\u00e4mlich gar nicht so einfach.<\/p>\n<h3>Die Mayflower II in Plymouth<\/h3>\nngg_shortcode_2_placeholder\n<h3>Bilder<\/h3>\nngg_shortcode_3_placeholder\n<h3><span style=\"font-size: 1.17em;\">Karte<\/span><\/h3>\n\n<table border=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td style=\"text-align: left;\"><a title=\"1. Anreise nach New York\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/1-anreise-nach-new-york\/\">\u2039\u00a0Zur\u00fcck<\/a><\/td>\n<td style=\"text-align: center;\"><a title=\"2011 USA Ost \u2013 \u00dcbersicht \u00fcber den Reiseverlauf\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2011-usa-ost-uebersicht-reiseverlauf\/\">Reiseverlauf<\/a><\/td>\n<td style=\"text-align: right;\"><a title=\"3. Boston\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/3-boston\/\">Weiter \u00a0\u203a<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Nach unserem Aufenthalt in New York sind wir weiter an der K\u00fcste entlang zum kleinen \u00d6rtchen Newport gefahren. Das \u00d6rtchen besticht durch seinen sch\u00f6n angelegten Hafen mit vielen Restaurants und Gesch\u00e4ften, leider war das Wetter nicht so sch\u00f6n, von daher haben wir beschlossen weiter zu fahren. <a class=\"more-link\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/\"><span class=\"screen-reader-text\">  2. Newport und Plymouth<\/span> weiterlesen<span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":593,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2011-usa-ostkueste"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2. Newport und Plymouth - Reiseberichte<\/title>\n<meta name=\"description\" content=\"Nach unserem Aufenthalt in New York sind wir weiter an der K\u00fcste entlang zum kleinen \u00d6rtchen Newport gefahren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2. Newport und Plymouth - Reiseberichte\" \/>\n<meta property=\"og:description\" content=\"Nach unserem Aufenthalt in New York sind wir weiter an der K\u00fcste entlang zum kleinen \u00d6rtchen Newport gefahren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/\" \/>\n<meta property=\"og:site_name\" content=\"Reiseberichte\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-25T15:10:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-03T08:29:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2011-usa-ost-2-plymouth-Beitragsbild-e1369494955626.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"115\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@chris_papp_de\" \/>\n<meta name=\"twitter:site\" content=\"@chris_papp_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chris\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2011-usa-ostkueste\\\/2-newport-und-plymouth\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2011-usa-ostkueste\\\/2-newport-und-plymouth\\\/\"},\"author\":{\"name\":\"Chris\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#\\\/schema\\\/person\\\/5c31a83093ce724f3bf8ae666747d594\"},\"headline\":\"2. Newport und Plymouth\",\"datePublished\":\"2013-05-25T15:10:12+00:00\",\"dateModified\":\"2020-08-03T08:29:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2011-usa-ostkueste\\\/2-newport-und-plymouth\\\/\"},\"wordCount\":480,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2011-usa-ostkueste\\\/2-newport-und-plymouth\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2011-usa-ost-2-plymouth-Beitragsbild-e1369494955626.jpg\",\"articleSection\":[\"2011 USA Ostk\u00fcste\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2011-usa-ostkueste\\\/2-newport-und-plymouth\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2011-usa-ostkueste\\\/2-newport-und-plymouth\\\/\",\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2011-usa-ostkueste\\\/2-newport-und-plymouth\\\/\",\"name\":\"2. Newport und Plymouth - Reiseberichte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2011-usa-ostkueste\\\/2-newport-und-plymouth\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2011-usa-ostkueste\\\/2-newport-und-plymouth\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2011-usa-ost-2-plymouth-Beitragsbild-e1369494955626.jpg\",\"datePublished\":\"2013-05-25T15:10:12+00:00\",\"dateModified\":\"2020-08-03T08:29:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#\\\/schema\\\/person\\\/5c31a83093ce724f3bf8ae666747d594\"},\"description\":\"Nach unserem Aufenthalt in New York sind wir weiter an der K\u00fcste entlang zum kleinen \u00d6rtchen Newport gefahren.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2011-usa-ostkueste\\\/2-newport-und-plymouth\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2011-usa-ostkueste\\\/2-newport-und-plymouth\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2011-usa-ostkueste\\\/2-newport-und-plymouth\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2011-usa-ost-2-plymouth-Beitragsbild-e1369494955626.jpg\",\"contentUrl\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/2011-usa-ost-2-plymouth-Beitragsbild-e1369494955626.jpg\",\"width\":200,\"height\":115},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2011-usa-ostkueste\\\/2-newport-und-plymouth\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reiseberichte\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Amerika\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"2011 USA Ostk\u00fcste\",\"item\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/reiseberichte\\\/amerika\\\/2011-usa-ostkueste\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"2. Newport und Plymouth\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#website\",\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/\",\"name\":\"Reiseberichte\",\"description\":\"In der Welt zu Hause\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/#\\\/schema\\\/person\\\/5c31a83093ce724f3bf8ae666747d594\",\"name\":\"Chris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g\",\"caption\":\"Chris\"},\"sameAs\":[\"https:\\\/\\\/familie-papp.de\",\"https:\\\/\\\/x.com\\\/chris_papp_de\"],\"url\":\"https:\\\/\\\/www.familie-papp.de\\\/reisen\\\/author\\\/chris\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2. Newport und Plymouth - Reiseberichte","description":"Nach unserem Aufenthalt in New York sind wir weiter an der K\u00fcste entlang zum kleinen \u00d6rtchen Newport gefahren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/","og_locale":"de_DE","og_type":"article","og_title":"2. Newport und Plymouth - Reiseberichte","og_description":"Nach unserem Aufenthalt in New York sind wir weiter an der K\u00fcste entlang zum kleinen \u00d6rtchen Newport gefahren.","og_url":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/","og_site_name":"Reiseberichte","article_published_time":"2013-05-25T15:10:12+00:00","article_modified_time":"2020-08-03T08:29:19+00:00","og_image":[{"width":200,"height":115,"url":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2011-usa-ost-2-plymouth-Beitragsbild-e1369494955626.jpg","type":"image\/jpeg"}],"author":"Chris","twitter_card":"summary_large_image","twitter_creator":"@chris_papp_de","twitter_site":"@chris_papp_de","twitter_misc":{"Verfasst von":"Chris","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/#article","isPartOf":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/"},"author":{"name":"Chris","@id":"https:\/\/www.familie-papp.de\/reisen\/#\/schema\/person\/5c31a83093ce724f3bf8ae666747d594"},"headline":"2. Newport und Plymouth","datePublished":"2013-05-25T15:10:12+00:00","dateModified":"2020-08-03T08:29:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/"},"wordCount":480,"commentCount":0,"image":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/#primaryimage"},"thumbnailUrl":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2011-usa-ost-2-plymouth-Beitragsbild-e1369494955626.jpg","articleSection":["2011 USA Ostk\u00fcste"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/","url":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/","name":"2. Newport und Plymouth - Reiseberichte","isPartOf":{"@id":"https:\/\/www.familie-papp.de\/reisen\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/#primaryimage"},"image":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/#primaryimage"},"thumbnailUrl":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2011-usa-ost-2-plymouth-Beitragsbild-e1369494955626.jpg","datePublished":"2013-05-25T15:10:12+00:00","dateModified":"2020-08-03T08:29:19+00:00","author":{"@id":"https:\/\/www.familie-papp.de\/reisen\/#\/schema\/person\/5c31a83093ce724f3bf8ae666747d594"},"description":"Nach unserem Aufenthalt in New York sind wir weiter an der K\u00fcste entlang zum kleinen \u00d6rtchen Newport gefahren.","breadcrumb":{"@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/#primaryimage","url":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2011-usa-ost-2-plymouth-Beitragsbild-e1369494955626.jpg","contentUrl":"https:\/\/www.familie-papp.de\/reisen\/wp-content\/uploads\/2013\/05\/2011-usa-ost-2-plymouth-Beitragsbild-e1369494955626.jpg","width":200,"height":115},{"@type":"BreadcrumbList","@id":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/2-newport-und-plymouth\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.familie-papp.de\/reisen\/"},{"@type":"ListItem","position":2,"name":"Reiseberichte","item":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/"},{"@type":"ListItem","position":3,"name":"Amerika","item":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/"},{"@type":"ListItem","position":4,"name":"2011 USA Ostk\u00fcste","item":"https:\/\/www.familie-papp.de\/reisen\/reiseberichte\/amerika\/2011-usa-ostkueste\/"},{"@type":"ListItem","position":5,"name":"2. Newport und Plymouth"}]},{"@type":"WebSite","@id":"https:\/\/www.familie-papp.de\/reisen\/#website","url":"https:\/\/www.familie-papp.de\/reisen\/","name":"Reiseberichte","description":"In der Welt zu Hause","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.familie-papp.de\/reisen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.familie-papp.de\/reisen\/#\/schema\/person\/5c31a83093ce724f3bf8ae666747d594","name":"Chris","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0cf5839b7ec8f1b70a67375077e5371750abe2976101128f778c8b2b7d7de6c4?s=96&d=mm&r=g","caption":"Chris"},"sameAs":["https:\/\/familie-papp.de","https:\/\/x.com\/chris_papp_de"],"url":"https:\/\/www.familie-papp.de\/reisen\/author\/chris\/"}]}},"_links":{"self":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts\/589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/comments?post=589"}],"version-history":[{"count":9,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts\/589\/revisions"}],"predecessor-version":[{"id":2193,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/posts\/589\/revisions\/2193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/media\/593"}],"wp:attachment":[{"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/media?parent=589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/categories?post=589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.familie-papp.de\/reisen\/wp-json\/wp\/v2\/tags?post=589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}